{"id":1607,"date":"2021-04-06T16:18:05","date_gmt":"2021-04-06T16:18:05","guid":{"rendered":"https:\/\/lisdatasolutions.sidnpre.com\/2021\/04\/06\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/"},"modified":"2026-03-27T08:30:43","modified_gmt":"2026-03-27T06:30:43","slug":"aplicaciones-de-la-inteligencia-artificial-en-la-industria","status":"publish","type":"post","link":"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/","title":{"rendered":"Aplicaciones de la inteligencia artificial en la industria"},"content":{"rendered":"\r\n\r\n\r\n<p>Como ya os hemos contado en anteriores post, la <a href=\"https:\/\/www.lisdatasolutions.com\/es\/consultoria-inteligencia-artificial\/\">Inteligencia Artificial<\/a> (AI) son aquellos <strong>desarrollos tecnol\u00f3gicos capaces de otorgar a las m\u00e1quinas modos de actuar similares a los desarrollados por los seres humanos<\/strong>. Se pueden simular capacidades motoras, un ejemplo ser\u00edan los brazos rob\u00f3ticos en cadenas de montaje, o cognitivas en aquellos sistemas capaces interactuar con el entorno y resolver problemas en funci\u00f3n de las variables interpretadas, como los sistemas de reconocimiento de im\u00e1genes. Dicho de otro modo, la Inteligencia Artificial percibe la realidad para la que ha sido programada, a trav\u00e9s de datos, y la analiza para, en funci\u00f3n de sus interpretaciones, generar una reacci\u00f3n autom\u00e1tica. Como se puede intuir, las <strong>aplicaciones en la industrial son innumerables<\/strong> y presentan importantes beneficios ligados a la eficiencia, productividad, rentabilidad, calidad y optimizaci\u00f3n de procesos. Veamos alguna de ellas:<\/p>\r\n\r\n\r\n\r\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_55 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\" role=\"button\"><label for=\"item-6a048fbe645ba\" ><span class=\"\"><span style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input aria-label=\"Toggle\" aria-label=\"item-6a048fbe645ba\"  type=\"checkbox\" id=\"item-6a048fbe645ba\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/#Vision_artificial\" title=\"Visi\u00f3n artificial\">Visi\u00f3n artificial<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/#Mantenimiento_predictivo\" title=\"Mantenimiento predictivo\">Mantenimiento predictivo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/#Prediccion_de_la_demanda\" title=\"Predicci\u00f3n de la demanda\">Predicci\u00f3n de la demanda<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/#Conclusion\" title=\"Conclusi\u00f3n\">Conclusi\u00f3n<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Vision_artificial\"><\/span><strong>Visi\u00f3n artificial<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p>Una rama de la Inteligencia Artificial, el Machine Learning, y dentro de este el desarrollo de redes neuronales convolucionales propias del Deep Learning, nos permite conseguir que los <strong>ordenadores lean im\u00e1genes, identifiquen elementos disonantes, y los clasifiquen en funci\u00f3n de patrones aprendidos<\/strong>, es decir, crear una <a href=\"https:\/\/www.lisdatasolutions.com\/es\/soluciones-de-vision-artificial\/\">visi\u00f3n artificial<\/a>. Pongamos un ejemplo para entenderlo mejor.<\/p>\r\n\r\n\r\n\r\n<p>Gracias al Deep Learning podemos desarrollar sistemas de vigilancia de grandes superficies. En estos casos las m\u00e1quinas conocen la imagen ideal de las instalaciones y aquellos elementos que pueden estar en las mismas, alertando de acontecimientos an\u00f3malos en el momento de su detecci\u00f3n. Si una c\u00e1mara apunta a una gran extensi\u00f3n portuaria destinada al RO-RO, el sistema sabe que puede haber coches y su ubicaci\u00f3n natural. Si en las im\u00e1genes captadas por los equipos de visionado apareciera una nube de humo, por ejemplo, el sistema lo detecta como intrusi\u00f3n y lanza una se\u00f1al de alarma con una identificaci\u00f3n probabil\u00edstica del elemento extra\u00f1o captado.<\/p>\r\n\r\n\r\n\r\n<p>Pero hay todav\u00eda un paso m\u00e1s. Las maquinas son entrenadas y aprenden autoenriqueciendo sus bases de datos en la medida en la que trabajan con nuevas im\u00e1genes, haciendo su aportaci\u00f3n cada vez m\u00e1s eficiente. Como vemos la utilidad de este tipo de aplicaci\u00f3n de la Inteligencia Artificial es enorme y extensiva, bajo los mismos fundamentos, al mantenimiento de grandes infraestructuras (carreteras, redes ferroviarias, l\u00edneas de alta tensi\u00f3n, transporte de hidrocarburos\u2026), al reconocimiento y clasificaci\u00f3n de elemento en cintas transportadoras, a los controles de calidad o la supervisi\u00f3n de vastas extensiones naturales (empresas madereras, valoraci\u00f3n de cat\u00e1strofes, control de superficies\u2026), por ampliar la n\u00f3mina de\u00a0 casos.<\/p>\r\n\r\n\r\n\r\n<h2><span class=\"ez-toc-section\" id=\"Mantenimiento_predictivo\"><\/span><strong>Mantenimiento predictivo<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p>Otra de las aplicaciones en las que m\u00e1s evidentes son los beneficios de la Inteligencia Artificial en la industria es el <a href=\"https:\/\/www.lisdatasolutions.com\/es\/mantenimiento-predictivo\/\">mantenimiento predictivo<\/a>. La maquinaria industrial es un activo vital en las empresas. De su rendimiento depende la productividad y, en consecuencia, la rentabilidad de las organizaciones.<\/p>\r\n\r\n\r\n\r\n<p>Las aver\u00edas y deterioros son inherentes a cualquier aparato o l\u00ednea. Su constante funcionamiento y la necesidad de que rindan bajo los par\u00e1metros establecidos, obligan a contar con pol\u00edticas de mantenimiento eficientes, que disminuyan los tiempos de parada y optimicen los recambios a efectuar y, por tanto, la inversi\u00f3n requerida.<\/p>\r\n\r\n\r\n\r\n<p>En este sentido, las nuevas tecnolog\u00edas disruptivas, acompa\u00f1adas del desarrollo y abaratamiento de la sens\u00f3rica, han contribuido a dar un paso de gigante, saltando del mantenimiento preventivo al mantenimiento predictivo. \u00bfY esto que supone? Poder <strong>adelantarse a los posibles fallos o mermas de las m\u00e1quinas, y realizar acciones correctoras de manera anticipada, minimizando el tiempo en el que las m\u00e1quinas est\u00e1n inoperativas<\/strong>.<\/p>\r\n\r\n\r\n\r\n<p>Gracias al an\u00e1lisis e interpretaci\u00f3n de los datos que se extraen de los propios aparatos (calor, vibraci\u00f3n, velocidad, horas de actividad\u2026), se pueden obtener alertas de las desviaciones del funcionamiento \u00f3ptimo en sus primeras etapas. Esta celeridad en la detecci\u00f3n de fallos permite implementar acciones correctoras en el momento en el que verdaderamente se requieren; eliminar los calendarios prefijados y, por tanto, las intervenciones no necesarias; y evitar grandes aver\u00edas que implican tiempos de paro muy superiores.<\/p>\r\n\r\n\r\n\r\n<h2><span class=\"ez-toc-section\" id=\"Prediccion_de_la_demanda\"><\/span><strong>Predicci\u00f3n de la demanda<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p>Con el mismo fundamento del sistema anterior, anticiparnos a lo que ocurrir\u00e1, nos encontramos con herramientas de predicci\u00f3n de la demanda. Como su propio nombre indica, las estimaciones futuras se refieren, en este caso, a las ventas que se van a realizar. <strong>Conocer de antemano la salida previsible de referencias, simplifica y eficienta operativas tan complejas como la gesti\u00f3n de almac\u00e9n, llevando la optimizaci\u00f3n del stock a sus m\u00e1ximas cotas de eficacia<\/strong>.<\/p>\r\n\r\n\r\n\r\n<p>Para conseguir las predicciones y operar en base a sus resultados, se compilan los datos internos y externos de la empresa (hist\u00f3ricos de ventas, tendencias del mercado, lead time de proveedores, \u00edndices de rotaci\u00f3n, etc.) y se tratan con algoritmos predictivos para obtener un escenario futuro de la demanda de nuestros productos, ajustado a la realidad de empresa y sector.<\/p>\r\n\r\n\r\n\r\n<p>De este modo, conociendo las necesidades inmediatas y futuras, la gesti\u00f3n de almac\u00e9n se vuelve mucho m\u00e1s sencilla y eficiente. Y no es un mero slogan publicitario. Estos sistemas posibilitan adecuar el stock, evitando roturas y sobre inventarios, ambas situaciones con importantes impactos econ\u00f3micos, la primera por la p\u00e9rdida de clientes, y la segunda a causa del capital inmovilizado y el riesgo de obsolescencia de referencias.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Adem\u00e1s, en herramientas como Purchases, nuestro propio asistente, el que mejor conocemos, es posible automatizar los procesos para recibir sugerencias directas de compras, basadas en las necesidades presentes y futuras, en el stock actual, en la capacidad de respuesta de los proveedores\u2026, y parametrizar alarmas con las que aumentar la operatividad del proceso. Toda la informaci\u00f3n es plasmada adem\u00e1s en cuadros de mando visuales e intuitivos para poder analizar la toda la informaci\u00f3n necesaria de un solo vistazo.<\/p>\r\n\r\n\r\n\r\n<h2><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span><strong>Conclusi\u00f3n<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p>Como vemos la Inteligencia Artificial se han convertido en el mejor de los apoyos que puede tener la industria. Sus aplicaciones son innumerables, solo hemos resaltado tres de ellas, pero puede aplicarse en todas las \u00e1reas de actividad, de cualquier sector, para mejorar multitud de tareas. Las empresas que quieran ser competitivas tienen que apoyarse en la Inteligencia Artificial para optimizar sus procesos. Hace unos a\u00f1os pod\u00eda parecer que su implementaci\u00f3n era solo para las grandes corporaciones, pero nada m\u00e1s lejos de la realidad, hoy en d\u00eda empresas de cualquier tama\u00f1o pueden beneficiarse de sus enormes potencialidades.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Como ya os hemos contado en anteriores post, la Inteligencia Artificial (AI) son aquellos desarrollos tecnol\u00f3gicos capaces de otorgar a las m\u00e1quinas modos de actuar similares a los desarrollados por los seres humanos. Se pueden simular capacidades motoras, un ejemplo ser\u00edan los brazos rob\u00f3ticos en cadenas de montaje, o cognitivas en aquellos sistemas capaces interactuar [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":1608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[111,43,1],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aplicaciones de la inteligencia artificial en la industria | LIS Data Solutions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aplicaciones de la inteligencia artificial en la industria | LIS Data Solutions\" \/>\n<meta property=\"og:description\" content=\"Como ya os hemos contado en anteriores post, la Inteligencia Artificial (AI) son aquellos desarrollos tecnol\u00f3gicos capaces de otorgar a las m\u00e1quinas modos de actuar similares a los desarrollados por los seres humanos. Se pueden simular capacidades motoras, un ejemplo ser\u00edan los brazos rob\u00f3ticos en cadenas de montaje, o cognitivas en aquellos sistemas capaces interactuar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/\" \/>\n<meta property=\"og:site_name\" content=\"LIS Data Solutions\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-06T16:18:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T06:30:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lisdatasolutions.com\/wp-content\/uploads\/2022\/07\/IA-industria-operario.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Natalia Andueza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalia Andueza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/\",\"url\":\"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/\",\"name\":\"Aplicaciones de la inteligencia artificial en la industria | LIS Data Solutions\",\"isPartOf\":{\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/#website\"},\"datePublished\":\"2021-04-06T16:18:05+00:00\",\"dateModified\":\"2026-03-27T06:30:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/#\/schema\/person\/b2748ac1971664b77f38389a77eb1fc7\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.lisdatasolutions.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aplicaciones de la inteligencia artificial en la industria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/#website\",\"url\":\"https:\/\/www.lisdatasolutions.com\/es\/\",\"name\":\"LIS Data Solutions\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lisdatasolutions.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/#\/schema\/person\/b2748ac1971664b77f38389a77eb1fc7\",\"name\":\"Natalia Andueza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/67d34db2d9aca971aeec85ef05923c86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/67d34db2d9aca971aeec85ef05923c86?s=96&d=mm&r=g\",\"caption\":\"Natalia Andueza\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aplicaciones de la inteligencia artificial en la industria | LIS Data Solutions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/","og_locale":"es_ES","og_type":"article","og_title":"Aplicaciones de la inteligencia artificial en la industria | LIS Data Solutions","og_description":"Como ya os hemos contado en anteriores post, la Inteligencia Artificial (AI) son aquellos desarrollos tecnol\u00f3gicos capaces de otorgar a las m\u00e1quinas modos de actuar similares a los desarrollados por los seres humanos. Se pueden simular capacidades motoras, un ejemplo ser\u00edan los brazos rob\u00f3ticos en cadenas de montaje, o cognitivas en aquellos sistemas capaces interactuar [&hellip;]","og_url":"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/","og_site_name":"LIS Data Solutions","article_published_time":"2021-04-06T16:18:05+00:00","article_modified_time":"2026-03-27T06:30:43+00:00","og_image":[{"width":1280,"height":684,"url":"https:\/\/www.lisdatasolutions.com\/wp-content\/uploads\/2022\/07\/IA-industria-operario.jpg","type":"image\/jpeg"}],"author":"Natalia Andueza","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Natalia Andueza","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/","url":"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/","name":"Aplicaciones de la inteligencia artificial en la industria | LIS Data Solutions","isPartOf":{"@id":"https:\/\/www.lisdatasolutions.com\/es\/#website"},"datePublished":"2021-04-06T16:18:05+00:00","dateModified":"2026-03-27T06:30:43+00:00","author":{"@id":"https:\/\/www.lisdatasolutions.com\/es\/#\/schema\/person\/b2748ac1971664b77f38389a77eb1fc7"},"breadcrumb":{"@id":"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lisdatasolutions.com\/es\/blog\/aplicaciones-de-la-inteligencia-artificial-en-la-industria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lisdatasolutions.com\/es\/"},{"@type":"ListItem","position":2,"name":"Aplicaciones de la inteligencia artificial en la industria"}]},{"@type":"WebSite","@id":"https:\/\/www.lisdatasolutions.com\/es\/#website","url":"https:\/\/www.lisdatasolutions.com\/es\/","name":"LIS Data Solutions","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lisdatasolutions.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.lisdatasolutions.com\/es\/#\/schema\/person\/b2748ac1971664b77f38389a77eb1fc7","name":"Natalia Andueza","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lisdatasolutions.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/67d34db2d9aca971aeec85ef05923c86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67d34db2d9aca971aeec85ef05923c86?s=96&d=mm&r=g","caption":"Natalia Andueza"}}]}},"_links":{"self":[{"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/posts\/1607"}],"collection":[{"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/comments?post=1607"}],"version-history":[{"count":3,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/posts\/1607\/revisions"}],"predecessor-version":[{"id":11511,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/posts\/1607\/revisions\/11511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/media\/1608"}],"wp:attachment":[{"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/media?parent=1607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/categories?post=1607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/tags?post=1607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}