{"id":11579,"date":"2026-04-16T08:18:13","date_gmt":"2026-04-16T06:18:13","guid":{"rendered":"https:\/\/www.lisdatasolutions.com\/?p=11579"},"modified":"2026-08-18T08:42:01","modified_gmt":"2026-08-18T06:42:01","slug":"proyecto-galaxia","status":"publish","type":"post","link":"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/","title":{"rendered":"LIS Data Solutions lidera la innovaci\u00f3n en IA ag\u00e9ntica con el proyecto GalaxIA"},"content":{"rendered":"<p>En LIS Data Solutions tenemos un esp\u00edritu innovador que nos impulsa a estar siempre a la vanguardia, por lo que nos enorgullece formar parte del consorcio con el que vamos a trabajar en el desarrollo de GalaxIA dentro de la convocatoria <strong>HAZITEK 2025<\/strong>, un programa de apoyo a la I+D empresarial del Gobierno Vasco.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_55 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\" role=\"button\"><label for=\"item-6a980c24812f9\" ><span class=\"\"><span style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input aria-label=\"Toggle\" aria-label=\"item-6a980c24812f9\"  type=\"checkbox\" id=\"item-6a980c24812f9\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/#%C2%BFQue_es_GalaxIA\" title=\"\u00bfQu\u00e9 es GalaxIA?\">\u00bfQu\u00e9 es GalaxIA?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/#Nuestro_papel_en_el_consorcio\" title=\"Nuestro papel en el consorcio\">Nuestro papel en el consorcio<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/#Un_impacto_real_en_la_industria_vasca\" title=\"Un impacto real en la industria vasca\">Un impacto real en la industria vasca<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/#Compromiso_con_la_innovacion_sostenible\" title=\"Compromiso con la innovaci\u00f3n sostenible\">Compromiso con la innovaci\u00f3n sostenible<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_GalaxIA\"><\/span><strong>\u00bfQu\u00e9 es GalaxIA?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>El proyecto nace con el objetivo de investigar y desarrollar una soluci\u00f3n tecnol\u00f3gica basada en <strong>IA ag\u00e9ntica<\/strong>. A diferencia de la IA generativa tradicional, que reacciona a las entradas del usuario, los agentes de IA de GalaxIA ser\u00e1n capaces de colaborar entre s\u00ed en lo que denominamos una <strong>\u00abconstelaci\u00f3n\u00bb<\/strong>. Estos sistemas podr\u00e1n orquestar acciones, planificar estrategias y ejecutar procesos complejos de forma aut\u00f3noma y proactiva, sin necesidad de intervenci\u00f3n humana constante.<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Nuestro_papel_en_el_consorcio\"><\/span><strong>Nuestro papel en el consorcio<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Como uno de los socios tecnol\u00f3gicos clave, nuestra labor se centra en:<\/p>\n<ul>\n<li><strong>Investigaci\u00f3n de estrategias de comunicaci\u00f3n y orquestaci\u00f3n:<\/strong> Dise\u00f1amos los mecanismos que permiten a los agentes descubrirse, autenticarse y colaborar de forma interoperable y segura.<\/li>\n<li><strong>Integraci\u00f3n en espacios de datos:<\/strong> Trabajamos para asegurar que los agentes puedan acceder y operar sobre datos externos de m\u00faltiples dominios, respetando siempre la soberan\u00eda y gobernanza del dato.<\/li>\n<li><strong>Desarrollo de soluciones industriales:<\/strong> Aportamos nuestro conocimiento en anal\u00edtica avanzada para transformar servicios tradicionales en arquitecturas basadas en agentes, mejorando la eficiencia operativa de las empresas vascas.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Un_impacto_real_en_la_industria_vasca\"><\/span><strong>Un impacto real en la industria vasca<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>GalaxIA no solo busca un avance te\u00f3rico, sino una validaci\u00f3n pr\u00e1ctica en sectores como la distribuci\u00f3n, la energ\u00eda, la m\u00e1quina-herramienta y el \u00e1mbito sociosanitario. Mediante el paradigma del <strong>Internet of Agents (IoA)<\/strong>, el proyecto permitir\u00e1 a las empresas automatizar tareas cognitivas complejas y crear nuevos modelos de negocio hiper-personalizados.<\/p>\n<p>Este proyecto se alinea con las estrategias europeas de digitalizaci\u00f3n y el Plan de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n (PCTI) Euskadi 2030, posicionando a nuestra regi\u00f3n a la vanguardia de la inteligencia artificial.<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Compromiso_con_la_innovacion_sostenible\"><\/span><strong>Compromiso con la innovaci\u00f3n sostenible<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Desde LIS Data Solutions, impulsamos un desarrollo de la IA que no solo sea potente, sino tambi\u00e9n <strong>\u00e9tico y sostenible<\/strong>. GalaxIA integra agentes de control y auditabilidad para garantizar un uso responsable de la tecnolog\u00eda y optimizar el consumo de recursos computacionales (Green Deployment).<\/p>\n<p>Estamos orgullosos de colaborar con socios de primer nivel como Eroski, Fagor Arrasate, Goizper, Mondragon Assembly, Ubikare y Xabet en este camino hacia una industria m\u00e1s inteligente y competitiva.<\/p>\n<p>&nbsp;<\/p>\n<p>Este proyecto (ZE-2025\/00002) est\u00e1 cofinanciado por el Gobierno Vasco y la Uni\u00f3n Europea a trav\u00e9s del Fondo Europeo de Desarrollo Regional 2021-2027 (FEDER) dentro del programa de ayudas de apoyo a la I+D empresarial &#8211; HAZITEK, con un importe de <span data-teams=\"true\">286.216,76\u20ac<\/span>.<\/p>\n<p><img class=\"alignnone wp-image-11580\" src=\"https:\/\/www.lisdatasolutions.com\/wp-content\/uploads\/2026\/04\/cartel_Galaxia-1-1024x724.png\" alt=\"Proyecto GALAXIA\" width=\"663\" height=\"469\" srcset=\"https:\/\/www.lisdatasolutions.com\/wp-content\/uploads\/2026\/04\/cartel_Galaxia-1-1024x724.png 1024w, https:\/\/www.lisdatasolutions.com\/wp-content\/uploads\/2026\/04\/cartel_Galaxia-1-300x212.png 300w, https:\/\/www.lisdatasolutions.com\/wp-content\/uploads\/2026\/04\/cartel_Galaxia-1-768x543.png 768w, https:\/\/www.lisdatasolutions.com\/wp-content\/uploads\/2026\/04\/cartel_Galaxia-1-1536x1086.png 1536w, https:\/\/www.lisdatasolutions.com\/wp-content\/uploads\/2026\/04\/cartel_Galaxia-1-2048x1448.png 2048w\" sizes=\"(max-width: 663px) 100vw, 663px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En LIS Data Solutions tenemos un esp\u00edritu innovador que nos impulsa a estar siempre a la vanguardia, por lo que nos enorgullece formar parte del consorcio con el que vamos a trabajar en el desarrollo de GalaxIA dentro de la convocatoria HAZITEK 2025, un programa de apoyo a la I+D empresarial del Gobierno Vasco. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":10438,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[186],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LIS Data Solutions lidera la innovaci\u00f3n en IA ag\u00e9ntica con el proyecto GalaxIA<\/title>\n<meta name=\"description\" content=\"Nos enorgullece formar parte del consorcio con el que vamos a trabajar en el desarrollo de GalaxIA dentro de la convocatoria HAZITEK 2025, un programa de apoyo a la I+D empresarial del Gobierno Vasco.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LIS Data Solutions lidera la innovaci\u00f3n en IA ag\u00e9ntica con el proyecto GalaxIA\" \/>\n<meta property=\"og:description\" content=\"Nos enorgullece formar parte del consorcio con el que vamos a trabajar en el desarrollo de GalaxIA dentro de la convocatoria HAZITEK 2025, un programa de apoyo a la I+D empresarial del Gobierno Vasco.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/\" \/>\n<meta property=\"og:site_name\" content=\"LIS Data Solutions\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-16T06:18:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-18T06:42:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lisdatasolutions.com\/wp-content\/uploads\/2025\/12\/Por-que-elegir-LIS.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Miguel Alvarez Iturraspe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miguel Alvarez Iturraspe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/\",\"url\":\"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/\",\"name\":\"LIS Data Solutions lidera la innovaci\u00f3n en IA ag\u00e9ntica con el proyecto GalaxIA\",\"isPartOf\":{\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/#website\"},\"datePublished\":\"2026-04-16T06:18:13+00:00\",\"dateModified\":\"2026-08-18T06:42:01+00:00\",\"author\":{\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/#\/schema\/person\/63ac1b20837ff2180d5f4c552aed4d62\"},\"description\":\"Nos enorgullece formar parte del consorcio con el que vamos a trabajar en el desarrollo de GalaxIA dentro de la convocatoria HAZITEK 2025, un programa de apoyo a la I+D empresarial del Gobierno Vasco.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.lisdatasolutions.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LIS Data Solutions lidera la innovaci\u00f3n en IA ag\u00e9ntica con el proyecto GalaxIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/#website\",\"url\":\"https:\/\/www.lisdatasolutions.com\/es\/\",\"name\":\"LIS Data Solutions\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lisdatasolutions.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/#\/schema\/person\/63ac1b20837ff2180d5f4c552aed4d62\",\"name\":\"Miguel Alvarez Iturraspe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.lisdatasolutions.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d7803c006d451f01d427c3f53022747d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d7803c006d451f01d427c3f53022747d?s=96&d=mm&r=g\",\"caption\":\"Miguel Alvarez Iturraspe\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LIS Data Solutions lidera la innovaci\u00f3n en IA ag\u00e9ntica con el proyecto GalaxIA","description":"Nos enorgullece formar parte del consorcio con el que vamos a trabajar en el desarrollo de GalaxIA dentro de la convocatoria HAZITEK 2025, un programa de apoyo a la I+D empresarial del Gobierno Vasco.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/","og_locale":"es_ES","og_type":"article","og_title":"LIS Data Solutions lidera la innovaci\u00f3n en IA ag\u00e9ntica con el proyecto GalaxIA","og_description":"Nos enorgullece formar parte del consorcio con el que vamos a trabajar en el desarrollo de GalaxIA dentro de la convocatoria HAZITEK 2025, un programa de apoyo a la I+D empresarial del Gobierno Vasco.","og_url":"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/","og_site_name":"LIS Data Solutions","article_published_time":"2026-04-16T06:18:13+00:00","article_modified_time":"2026-08-18T06:42:01+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/www.lisdatasolutions.com\/wp-content\/uploads\/2025\/12\/Por-que-elegir-LIS.png","type":"image\/png"}],"author":"Miguel Alvarez Iturraspe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Miguel Alvarez Iturraspe","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/","url":"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/","name":"LIS Data Solutions lidera la innovaci\u00f3n en IA ag\u00e9ntica con el proyecto GalaxIA","isPartOf":{"@id":"https:\/\/www.lisdatasolutions.com\/es\/#website"},"datePublished":"2026-04-16T06:18:13+00:00","dateModified":"2026-08-18T06:42:01+00:00","author":{"@id":"https:\/\/www.lisdatasolutions.com\/es\/#\/schema\/person\/63ac1b20837ff2180d5f4c552aed4d62"},"description":"Nos enorgullece formar parte del consorcio con el que vamos a trabajar en el desarrollo de GalaxIA dentro de la convocatoria HAZITEK 2025, un programa de apoyo a la I+D empresarial del Gobierno Vasco.","breadcrumb":{"@id":"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lisdatasolutions.com\/es\/blog\/proyecto-galaxia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lisdatasolutions.com\/es\/"},{"@type":"ListItem","position":2,"name":"LIS Data Solutions lidera la innovaci\u00f3n en IA ag\u00e9ntica con el proyecto GalaxIA"}]},{"@type":"WebSite","@id":"https:\/\/www.lisdatasolutions.com\/es\/#website","url":"https:\/\/www.lisdatasolutions.com\/es\/","name":"LIS Data Solutions","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lisdatasolutions.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.lisdatasolutions.com\/es\/#\/schema\/person\/63ac1b20837ff2180d5f4c552aed4d62","name":"Miguel Alvarez Iturraspe","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lisdatasolutions.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d7803c006d451f01d427c3f53022747d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d7803c006d451f01d427c3f53022747d?s=96&d=mm&r=g","caption":"Miguel Alvarez Iturraspe"}}]}},"_links":{"self":[{"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/posts\/11579"}],"collection":[{"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/comments?post=11579"}],"version-history":[{"count":2,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/posts\/11579\/revisions"}],"predecessor-version":[{"id":11583,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/posts\/11579\/revisions\/11583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/media\/10438"}],"wp:attachment":[{"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/media?parent=11579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/categories?post=11579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lisdatasolutions.com\/es\/wp-json\/wp\/v2\/tags?post=11579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}